{"id":4039,"date":"2022-04-08T16:14:37","date_gmt":"2022-04-08T14:14:37","guid":{"rendered":"https:\/\/schabziger.ch\/homepage-2\/"},"modified":"2026-01-13T08:37:06","modified_gmt":"2026-01-13T07:37:06","slug":"homepage-2","status":"publish","type":"page","link":"https:\/\/schabziger.ch\/en\/","title":{"rendered":"Homepage"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full ah-img-display-fullwidth ah-img-display-tablet-desktop\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1067\" src=\"https:\/\/schabziger.ch\/wp-content\/uploads\/2026\/01\/2601_Geska_Website_Header_1920x800px_DE_FR_EN-scaled.jpg\" alt=\"\" class=\"wp-image-4366\" srcset=\"https:\/\/schabziger.ch\/wp-content\/uploads\/2026\/01\/2601_Geska_Website_Header_1920x800px_DE_FR_EN-scaled.jpg 2560w, https:\/\/schabziger.ch\/wp-content\/uploads\/2026\/01\/2601_Geska_Website_Header_1920x800px_DE_FR_EN-300x125.jpg 300w, https:\/\/schabziger.ch\/wp-content\/uploads\/2026\/01\/2601_Geska_Website_Header_1920x800px_DE_FR_EN-1024x427.jpg 1024w, https:\/\/schabziger.ch\/wp-content\/uploads\/2026\/01\/2601_Geska_Website_Header_1920x800px_DE_FR_EN-768x320.jpg 768w, https:\/\/schabziger.ch\/wp-content\/uploads\/2026\/01\/2601_Geska_Website_Header_1920x800px_DE_FR_EN-1536x640.jpg 1536w, https:\/\/schabziger.ch\/wp-content\/uploads\/2026\/01\/2601_Geska_Website_Header_1920x800px_DE_FR_EN-2048x854.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-full ah-img-display-fullwidth ah-img-display-mobile\"><img loading=\"lazy\" decoding=\"async\" width=\"1988\" height=\"2560\" src=\"https:\/\/schabziger.ch\/wp-content\/uploads\/2026\/01\/2025_Geska_Website_Header_Mobile_1242x1600px_DE_FR_EN-scaled.jpg\" alt=\"\" class=\"wp-image-4369\" srcset=\"https:\/\/schabziger.ch\/wp-content\/uploads\/2026\/01\/2025_Geska_Website_Header_Mobile_1242x1600px_DE_FR_EN-scaled.jpg 1988w, https:\/\/schabziger.ch\/wp-content\/uploads\/2026\/01\/2025_Geska_Website_Header_Mobile_1242x1600px_DE_FR_EN-233x300.jpg 233w, https:\/\/schabziger.ch\/wp-content\/uploads\/2026\/01\/2025_Geska_Website_Header_Mobile_1242x1600px_DE_FR_EN-795x1024.jpg 795w, https:\/\/schabziger.ch\/wp-content\/uploads\/2026\/01\/2025_Geska_Website_Header_Mobile_1242x1600px_DE_FR_EN-768x989.jpg 768w, https:\/\/schabziger.ch\/wp-content\/uploads\/2026\/01\/2025_Geska_Website_Header_Mobile_1242x1600px_DE_FR_EN-1193x1536.jpg 1193w, https:\/\/schabziger.ch\/wp-content\/uploads\/2026\/01\/2025_Geska_Website_Header_Mobile_1242x1600px_DE_FR_EN-1590x2048.jpg 1590w\" sizes=\"auto, (max-width: 1988px) 100vw, 1988px\" \/><\/figure>\n\n<section class=\"white\">\n\t<div class=\"content max\">\n\t\t\t\n\n\n<h2 class=\"wp-block-heading\">The finest from Glarus<\/h2>\n<div id=\"fwdr3dcovDiv0\"><\/div><div id=\"fwdr3dcovPlaylistProdukte\" class=\"fwdr3dcov-gallery\"><div data-cat=\"Produkte\"><ul><li data-rl-src=\"link:https:\/\/schabziger.ch\/produkte\" data-rl-target=\"_self\"><\/li><li data-thumb-src=\"https:\/\/schabziger.ch\/wp-content\/uploads\/2025\/10\/Wuerz-Mi_RGB-1-scaled.png\"><\/li><\/ul><ul><li data-rl-src=\"link:https:\/\/schabziger.ch\/produkte\" data-rl-target=\"_self\"><\/li><li data-thumb-src=\"https:\/\/schabziger.ch\/wp-content\/uploads\/2025\/10\/Glarissa_RGB.png\"><\/li><\/ul><ul><li data-rl-src=\"link:https:\/\/schabziger.ch\/produkte\" data-rl-target=\"_self\"><\/li><li data-thumb-src=\"https:\/\/schabziger.ch\/wp-content\/uploads\/2025\/10\/Zigerbutter_RGB-scaled.png\"><\/li><\/ul><ul><li data-rl-src=\"link:https:\/\/schabziger.ch\/produkte\" data-rl-target=\"_self\"><\/li><li data-thumb-src=\"https:\/\/schabziger.ch\/wp-content\/uploads\/2025\/10\/Zibu_CMYK-scaled.png\"><\/li><\/ul><ul><li data-rl-src=\"link:https:\/\/schabziger.ch\/produkte\" data-rl-target=\"_self\"><\/li><li data-thumb-src=\"https:\/\/schabziger.ch\/wp-content\/uploads\/2025\/04\/Gewuerz_Reibkease_RGB-2-scaled.png\"><\/li><\/ul><ul><li data-rl-src=\"link:https:\/\/schabziger.ch\/produkte\" data-rl-target=\"_self\"><\/li><li data-thumb-src=\"https:\/\/schabziger.ch\/wp-content\/uploads\/2025\/10\/Stoeckli_RGB-scaled.png\"><\/li><\/ul><ul><li data-rl-src=\"link:https:\/\/schabziger.ch\/produkte\" data-rl-target=\"_self\"><\/li><li data-thumb-src=\"https:\/\/schabziger.ch\/wp-content\/uploads\/2025\/10\/Gruessli_RGB-scaled.png\"><\/li><\/ul><ul><li data-rl-src=\"link:https:\/\/schabziger.ch\/produkte\" data-rl-target=\"_self\"><\/li><li data-thumb-src=\"https:\/\/schabziger.ch\/wp-content\/uploads\/2025\/04\/Stoeckli_Chili_RGB-1.png\"><\/li><\/ul><ul><li data-rl-src=\"link:https:\/\/schabziger.ch\/produkte\" data-rl-target=\"_self\"><\/li><li data-thumb-src=\"https:\/\/schabziger.ch\/wp-content\/uploads\/2025\/04\/Stoeckli_Trueffel_RGB-2.png\"><\/li><\/ul><ul><li data-rl-src=\"link:https:\/\/schabziger.ch\/angebot-duo\/\" data-rl-target=\"_blank\"><\/li><li data-thumb-src=\"https:\/\/schabziger.ch\/wp-content\/uploads\/2025\/10\/Mockup_Schabziger_Trueffel_Karussell.png\"><\/li><\/ul><ul><li data-rl-src=\"link:https:\/\/schabziger.ch\/angebot-duo\/\" data-rl-target=\"_blank\"><\/li><li data-thumb-src=\"https:\/\/schabziger.ch\/wp-content\/uploads\/2023\/09\/Mockup_Chili_Trueffel_1160x800-1.png\"><\/li><\/ul><\/div><\/div>\n<\/div><\/section>\n<section class=\"gray\">\n\t<div class=\"content max\">\n\t\t\t\n\n\n<h1 class=\"wp-block-heading\">Recipes <a href=\"https:\/\/schabziger.ch\/en\/recipes\/\">All recipes &gt;<\/a> <\/h1>\n<\/div><div class=\"content max posts\">\n\t\t\t<a style=\"background:none\">\t\n\t\t\t\t<figure style=\"background:url(\/wp-content\/uploads\/2025\/01\/GSZ_LassEs_rezepte_de_1_neu.svg);background-size:contain;background-repeat: no-repeat;\"><\/figure>\n\t\t\t<\/a>\n\t\t\n\t\t\t<a href=\"https:\/\/schabziger.ch\/en\/recipe\/asparagus-with-glaronaise-sauce\/\" style=\"\">\t\n\t\t\t\t<figure style=\"background-image:url(https:\/\/schabziger.ch\/wp-content\/uploads\/2022\/05\/spargeln_mit_sauce_glaronaise.jpg)\" title=\"Asparagus with &#8220;Glaronaise&#8221; sauce\"><\/figure>\n\t\t\t<\/a>\n\t\t\n\t\t\t<a href=\"https:\/\/schabziger.ch\/en\/recipe\/original-zigerhoernli\/\" style=\"\">\t\n\t\t\t\t<figure style=\"background-image:url(https:\/\/schabziger.ch\/wp-content\/uploads\/2022\/05\/Zigerho\u0308rnli.jpg)\" title=\"Original Zigerh\u00f6rnli\"><\/figure>\n\t\t\t<\/a>\n\t\t\n<\/div><\/section><section class=\"green\">\n\t<div class=\"content max blob\">\n\t\t<img decoding=\"async\" src=\"https:\/\/schabziger.ch\/wp-content\/uploads\/2022\/05\/gsz_02_portrait_slideshow_geschichte_1.jpeg\" alt=\"\">\n\t\t<span>\n\t\t\t<h2>Schabziger history<\/h2>\n\t\t\t<span class=\"white\">\n\t\t\t\t<p>The GLARNER SCHABZIGER looks back on a history of over a thousand years. From the 8th century until 1395, the Glarnerland was owned by the S\u00e4ckingen monastery.<\/p>\n<p><a href=\"https:\/\/schabziger.ch\/en\/portrait\/\">To the whole story<\/a><\/p>\n\t\t\t<\/span>\n\t\t<\/span>\n\t<\/div>\n\t<div class=\"content max\">\n\n<\/div><\/section>\n<section class=\"gray\">\n\t<div class=\"content max\">\n\t\t\t\n\n\n<h1 class=\"wp-block-heading\">News <a href=\"https:\/\/schabziger.ch\/en\/news\/\">All News &gt;<\/a> <\/h1>\n<\/div><div class=\"content max posts\" style=\"margin-top:0\"><select oninput=\"location.href = '\/news\/?Y='+this.value\"><option value=\"\">Filter by years<\/option><option value=\"\">Show all<\/option><option >2026<\/option><option >2025<\/option><option >2024<\/option><option >2023<\/option><option >2022<\/option><option >2021<\/option><option >2020<\/option><option >2019<\/option><option >2018<\/option><option >2017<\/option><option >2016<\/option><\/select><\/div><div class=\"content max posts m4\">\n\t\t\t<a href=\"https:\/\/schabziger.ch\/en\/media-release-of-the-oc-esaf-2025-glarnerland\/\" style=\"grid-column: 1 \/ 3\" class=\"\">\n\t\t\t\t<figure style=\"background-image:url(https:\/\/schabziger.ch\/wp-content\/uploads\/2022\/04\/schabziger-munipartner.jpg)\" title=\"Media release of the OC ESAF 2025 Glarnerland +\"><\/figure>\n\t\t\t\t<small>21. December 2021<\/small>\n\t\t\t\t<span>Since the contract was awarded for Switzerland's largest sports and folk festival on this year's Fridolin's Day, the preparatory work has been in full swing.<\/span>\n\t\t\t\t<span>Read more<\/span>\n\t\t\t<\/a>\n\t\t\n\t\t\t\t<form action=\"https:\/\/geska.us14.list-manage.com\/subscribe\/post?u=1cf5c3c9758bac2455740f2c3&amp;id=a6d7fc7fc8\" method=\"post\" target=\"_blank\">\n\t\t\t\t\t<strong>Interested in exciting news about our Glarner Schabziger?<\/strong>\n\t\t\t\t\t<span>Then sign up for our newsletter right away!<\/span>\n\t\t\t\t\t<label>\n\t\t\t\t\t\tE-Mail-Adresse\n\t\t\t\t\t\t<input type=\"email\" name=\"EMAIL\" required>\n\t\t\t\t\t<\/label>\n\t\t\t\t\t<input type=\"submit\" value=\"Subscribe to newsletter\">\n\t\t\t\t<\/form>\n\t\t\t\n\t\t\t<a href=\"https:\/\/schabziger.ch\/en\/winners-are-drawn\/\" style=\"\" class=\"\">\n\t\t\t\t<figure style=\"background-image:url(https:\/\/schabziger.ch\/wp-content\/uploads\/2022\/05\/schabziger-wettbewrb-3.jpg)\" title=\"Winners are drawn\"><\/figure>\n\t\t\t\t<small>28. October 2021<\/small>\n\t\t\t\t<span>This summer we launched a contest and asked the participants for their opinion on the taste of Schabziger in a charmingly provocative way.  <\/span>\n\t\t\t\t<span>Read more<\/span>\n\t\t\t<\/a>\n\t\t\n\t\t\t<a href=\"https:\/\/schabziger.ch\/en\/a-look-behind-the-scenes-plant-tour\/\" style=\"\" class=\"\">\n\t\t\t\t<figure style=\"background-image:url(https:\/\/schabziger.ch\/wp-content\/uploads\/2022\/05\/gsz_04_produkte_slideshow_produktion-zibu_2.jpg)\" title=\"A look behind the scenes &#8211; plant tour\"><\/figure>\n\t\t\t\t<small>26. October 2021<\/small>\n\t\t\t\t<span>Visit us and experience the Glarner Schabziger up close and watch our employees produce Switzerland's oldest brand product.<\/span>\n\t\t\t\t<span>Read more<\/span>\n\t\t\t<\/a>\n\t\t\n\t\t\t<a href=\"https:\/\/schabziger.ch\/en\/glarus-gazpacho-recipe\/\" style=\"\" class=\"\">\n\t\t\t\t<figure style=\"background-image:url(https:\/\/schabziger.ch\/wp-content\/uploads\/2022\/05\/Glarner_Gazpacho_schabziger_tomate.jpg)\" title=\"Glarus gazpacho recipe\"><\/figure>\n\t\t\t\t<small>20. October 2021<\/small>\n\t\t\t\t<span>The cold Spanish cult soup for hot summer days is also available in a delicious Glarus version. And the best part is that the preparation is very simple!<\/span>\n\t\t\t\t<span>Read more<\/span>\n\t\t\t<\/a>\n\t\t\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>The finest from Glarus Recipes All recipes &gt; News All News &gt;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-4039","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Homepage - Schabziger<\/title>\n<meta name=\"description\" content=\"Welcome to the official website of Glarner Schabzer, the oldest brand product in the world!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schabziger.ch\/en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Homepage - Schabziger\" \/>\n<meta property=\"og:description\" content=\"Welcome to the official website of Glarner Schabzer, the oldest brand product in the world!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schabziger.ch\/en\/\" \/>\n<meta property=\"og:site_name\" content=\"Schabziger\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-13T07:37:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schabziger.ch\/wp-content\/uploads\/2026\/01\/2601_Geska_Website_Header_1920x800px_DE_FR_EN-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schabziger.ch\\\/en\\\/\",\"url\":\"https:\\\/\\\/schabziger.ch\\\/en\\\/\",\"name\":\"Homepage - Schabziger\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schabziger.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/schabziger.ch\\\/en\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/schabziger.ch\\\/en\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schabziger.ch\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/2601_Geska_Website_Header_1920x800px_DE_FR_EN-scaled.jpg\",\"datePublished\":\"2022-04-08T14:14:37+00:00\",\"dateModified\":\"2026-01-13T07:37:06+00:00\",\"description\":\"Welcome to the official website of Glarner Schabzer, the oldest brand product in the world!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schabziger.ch\\\/en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schabziger.ch\\\/en\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/schabziger.ch\\\/en\\\/#primaryimage\",\"url\":\"https:\\\/\\\/schabziger.ch\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/2601_Geska_Website_Header_1920x800px_DE_FR_EN-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/schabziger.ch\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/2601_Geska_Website_Header_1920x800px_DE_FR_EN-scaled.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schabziger.ch\\\/en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schabziger.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Homepage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schabziger.ch\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/schabziger.ch\\\/en\\\/\",\"name\":\"Schabziger\",\"description\":\"Uurw\u00fcrzig guet\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schabziger.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Homepage - Schabziger","description":"Welcome to the official website of Glarner Schabzer, the oldest brand product in the world!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schabziger.ch\/en\/","og_locale":"en_US","og_type":"article","og_title":"Homepage - Schabziger","og_description":"Welcome to the official website of Glarner Schabzer, the oldest brand product in the world!","og_url":"https:\/\/schabziger.ch\/en\/","og_site_name":"Schabziger","article_modified_time":"2026-01-13T07:37:06+00:00","og_image":[{"width":2560,"height":1067,"url":"https:\/\/schabziger.ch\/wp-content\/uploads\/2026\/01\/2601_Geska_Website_Header_1920x800px_DE_FR_EN-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schabziger.ch\/en\/","url":"https:\/\/schabziger.ch\/en\/","name":"Homepage - Schabziger","isPartOf":{"@id":"https:\/\/schabziger.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/schabziger.ch\/en\/#primaryimage"},"image":{"@id":"https:\/\/schabziger.ch\/en\/#primaryimage"},"thumbnailUrl":"https:\/\/schabziger.ch\/wp-content\/uploads\/2026\/01\/2601_Geska_Website_Header_1920x800px_DE_FR_EN-scaled.jpg","datePublished":"2022-04-08T14:14:37+00:00","dateModified":"2026-01-13T07:37:06+00:00","description":"Welcome to the official website of Glarner Schabzer, the oldest brand product in the world!","breadcrumb":{"@id":"https:\/\/schabziger.ch\/en\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schabziger.ch\/en\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/schabziger.ch\/en\/#primaryimage","url":"https:\/\/schabziger.ch\/wp-content\/uploads\/2026\/01\/2601_Geska_Website_Header_1920x800px_DE_FR_EN-scaled.jpg","contentUrl":"https:\/\/schabziger.ch\/wp-content\/uploads\/2026\/01\/2601_Geska_Website_Header_1920x800px_DE_FR_EN-scaled.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/schabziger.ch\/en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schabziger.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Homepage"}]},{"@type":"WebSite","@id":"https:\/\/schabziger.ch\/en\/#website","url":"https:\/\/schabziger.ch\/en\/","name":"Schabziger","description":"Uurw\u00fcrzig guet","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schabziger.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/schabziger.ch\/en\/wp-json\/wp\/v2\/pages\/4039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schabziger.ch\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/schabziger.ch\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/schabziger.ch\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/schabziger.ch\/en\/wp-json\/wp\/v2\/comments?post=4039"}],"version-history":[{"count":4,"href":"https:\/\/schabziger.ch\/en\/wp-json\/wp\/v2\/pages\/4039\/revisions"}],"predecessor-version":[{"id":4374,"href":"https:\/\/schabziger.ch\/en\/wp-json\/wp\/v2\/pages\/4039\/revisions\/4374"}],"wp:attachment":[{"href":"https:\/\/schabziger.ch\/en\/wp-json\/wp\/v2\/media?parent=4039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}